{"id":98298,"date":"2022-04-05T11:02:05","date_gmt":"2022-04-05T11:02:05","guid":{"rendered":"https:\/\/divigaragedoorrepair.divifixer.com\/?page_id=53"},"modified":"2026-06-24T06:46:24","modified_gmt":"2026-06-24T06:46:24","slug":"services-list","status":"publish","type":"page","link":"https:\/\/divithemeshub.com\/garagedoortheme\/services-list\/","title":{"rendered":"Services List"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_0 et_pb_row et_block_row\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><p>Services List<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_breadcrumbs_0 et_pb_breadcrumbs et_pb_module et_flex_module\"><div class=\"et_pb_module_inner\"><nav class=\"et_pb_breadcrumbs--trail\" aria-label=\"Breadcrumb\"><a href=\"https:\/\/divithemeshub.com\/garagedoortheme\" class=\"et_pb_breadcrumbs--breadcrumb et_pb_breadcrumbs--home\">Home<\/a><span class=\"et_pb_breadcrumbs--separator\">\/<\/span><span class=\"et_pb_breadcrumbs--current et_pb_breadcrumbs--breadcrumb\">Archives<\/span><\/nav><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><span class=\"et_pb_background_pattern\"><\/span>\n<div class=\"et_pb_row_2 et_pb_row et_pb_equal_columns et_pb_gutters1 et_block_row\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue074<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h5 class=\"et_pb_module_header\">Residential Services<\/h5><div class=\"et_pb_blurb_description\"><p>Pretium quis quam laoreet efficitur liquam volutpe sem consequat consequat imperdiet.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Bent Door Panels \/ Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Broken Springs or Opener<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Gates &amp; Gate Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_3_wrapper\"><a class=\"et_pb_button_3 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Remote Control Issues<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_4_wrapper\"><a class=\"et_pb_button_4 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Off Track Doors &amp; Broken Cables<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_5_wrapper\"><a class=\"et_pb_button_5 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module dct_btn\" href=\"\">View More<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf155<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">STARTS FROM $90<\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_pb_equal_columns et_pb_gutters1 et_block_row\">\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf793<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h5 class=\"et_pb_module_header\">Commercial Services<\/h5><div class=\"et_pb_blurb_description\"><p>Pretium quis quam laoreet efficitur liquam volutpe sem consequat consequat imperdiet.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_6_wrapper\"><a class=\"et_pb_button_6 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Bent Door Panels \/ Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_7_wrapper\"><a class=\"et_pb_button_7 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Broken Springs or Opener<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_8_wrapper\"><a class=\"et_pb_button_8 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Gates &amp; Gate Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_9_wrapper\"><a class=\"et_pb_button_9 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Remote Control Issues<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_10_wrapper\"><a class=\"et_pb_button_10 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Off Track Doors &amp; Broken Cables<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_11_wrapper\"><a class=\"et_pb_button_11 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module dct_btn\" href=\"\">View More<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf155<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">STARTS FROM $90<\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_pb_equal_columns et_pb_gutters1 et_block_row\">\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf52b<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h5 class=\"et_pb_module_header\">Automatic Garage Door<\/h5><div class=\"et_pb_blurb_description\"><p>Pretium quis quam laoreet efficitur liquam volutpe sem consequat consequat imperdiet.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_12_wrapper\"><a class=\"et_pb_button_12 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Bent Door Panels \/ Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_13_wrapper\"><a class=\"et_pb_button_13 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Broken Springs or Opener<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_14_wrapper\"><a class=\"et_pb_button_14 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Gates &amp; Gate Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_15_wrapper\"><a class=\"et_pb_button_15 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Remote Control Issues<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_16_wrapper\"><a class=\"et_pb_button_16 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Off Track Doors &amp; Broken Cables<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_17_wrapper\"><a class=\"et_pb_button_17 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module dct_btn\" href=\"\">View More<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf155<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">STARTS FROM $90<\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_pb_equal_columns et_pb_gutters1 et_block_row\">\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_flex_module\"><div class=\"et_pb_blurb_content et_flex_module\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf6d9<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h5 class=\"et_pb_module_header\">New Door Installation<\/h5><div class=\"et_pb_blurb_description\"><p>Pretium quis quam laoreet efficitur liquam volutpe sem consequat consequat imperdiet.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_18_wrapper\"><a class=\"et_pb_button_18 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Bent Door Panels \/ Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_19_wrapper\"><a class=\"et_pb_button_19 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Broken Springs or Opener<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_20_wrapper\"><a class=\"et_pb_button_20 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Gates &amp; Gate Openers<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_21_wrapper\"><a class=\"et_pb_button_21 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Remote Control Issues<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_22_wrapper\"><a class=\"et_pb_button_22 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\" data-icon=\"\uf058\">Off Track Doors &amp; Broken Cables<\/a><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_23_wrapper\"><a class=\"et_pb_button_23 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module dct_btn\" href=\"\">View More<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_7 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf155<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">STARTS FROM $40<\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-98298","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/pages\/98298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/comments?post=98298"}],"version-history":[{"count":2,"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/pages\/98298\/revisions"}],"predecessor-version":[{"id":100945,"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/pages\/98298\/revisions\/100945"}],"wp:attachment":[{"href":"https:\/\/divithemeshub.com\/garagedoortheme\/wp-json\/wp\/v2\/media?parent=98298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}